{"id":1397,"date":"2024-09-15T15:50:17","date_gmt":"2024-09-15T15:50:17","guid":{"rendered":"https:\/\/expatcircle.com\/cms\/de\/?p=1397"},"modified":"2025-02-15T15:55:28","modified_gmt":"2025-02-15T15:55:28","slug":"einfuehrung-in-den-pt-lebensstil","status":"publish","type":"post","link":"https:\/\/expatcircle.com\/cms\/de\/einfuehrung-in-den-pt-lebensstil\/","title":{"rendered":"Einfuehrung in den PT Lebensstil."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1398\" src=\"https:\/\/expatcircle.com\/cms\/de\/wp-content\/uploads\/2025\/02\/plane.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">&#8220;Nationen haben ihre alte Allmacht verloren, die patriotischen Verbindungen brechen. Nationen werden bedeutungslos, wir gehen und leben wo wir wollen. Dampfkraft erm\u00f6glicht ihnen das Gesetz zu w\u00e4hlen, unter dem sie leben wollen. Geld erm\u00f6glicht Ihnen Freiheit&#8221;<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Ralph Waldo Emerson, 1861<\/span><\/p>\n<\/blockquote>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm8\">\u00a0<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm8\">\u00a0<\/span><\/strong><span class=\"tm7\">Sie arbeiten lieber f\u00fcr sich selbst und nicht f\u00fcr den Staat? Sie wollen ungest\u00f6rt Marihuana rauchen? Sie f\u00fchlen sich wohler, wenn sie die Kalaschnikow im Schrank stehen haben? Sie stehen darauf, legal eine 14 j\u00e4hrige Freundin haben zu d\u00fcrfen? Sie essen gerne Hundefleisch? Sie beabsichtigen drei Frauen zu heiraten? Sie bestehen auf einem Bankgeheimnis? Meinungsfreiheit? Keine MwSt.? Strand und Sonne? Ziehen sie nach Ancapistan! Doch wie liegt Ancapistan? Was gelten f\u00fcr Einreisebestimmungen? Wie hoch sind die H\u00fcrden? Meine geneigten Leser, Sie werden \u00fcberrascht sein: Ancapistan kann \u00fcberall liegen und die Einreisebestimmungen sind f\u00fcr Inhaber eines BRD Reisepasses vergleichsweise einfach . Im Prinzip machen sie nichts anderes, als jeder gro\u00dfe deutsche Konzern: Dieser l\u00e4sst in Indien entwickeln, in China produzieren, in der Tschechei verwalten, verkauft in Deutschland und versteuert in Irland Nebenbei l\u00e4sst er sein Copyright und den Patentschutz steuerfinanziert durchsetzen und dank dem Lobbyismus der Konzerne gibt es in Deutschland mittlerweile h\u00f6here Strafen f\u00fcr das Kopieren einer Musik CD als f\u00fcr Kinderpornographie. Zeit zu gehen! <\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Das zum Konzern \u00e4quivalente Konzept f\u00fcr Privatpersonen, PT genannt, wurde von Harry Schultz entwickelt und schlie\u00dflich von Dr. WG Hill verfeinert. PT steht dabei f\u00fcr verschiedene Abk\u00fcrzungen und Bedeutungen wie \u201cPermanent Traveler (\u201cSt\u00e4ndiger Reisender\u201d), \u201cPermanent Tourist\u201d (\u201cSt\u00e4ndiger Tourist\u201d) oder \u201cPrevious Taxpayer\u201d (\u201cEhemaliger Steuerzahler\u201d). Dahinter steht unter anderem der Grundgedanke, dass man durch Planung zeitlich stets nur begrenzter Aufenthalte in einem Land sowie entsprechende regelm\u00e4\u00dfige Verlegung des eigenen De-facto-Wohnsitzes in andere Jurisdiktionen in keiner davon steuerpflichtig wird. Au\u00dferdem k\u00f6nnen Sie sich auf diese Weise auch anderen administrativen Zugriffen, sprich Schikanen, geschickter entziehen, wodurch Sie ein St\u00fcck Selbstbestimmung zur\u00fcckgewinnen. Genie\u00dfen sie alles dort, wo man Verst\u00e4ndnis f\u00fcr ihre Bed\u00fcrfnisse hat. Ob Bankgeheimnis auf den Bahamas, die 14 j\u00e4hrige Freundin in Deutschland, die Marihuana-T\u00fcte in Amsterdam, den Steuersatz von Dubai, ein leckeres Hundesteak in Asien, die Null-MwSt. von New Hampshire oder eben eine Kalaschnikow in Texas. <\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Nur k\u00f6nnen sie eben nicht die Kalaschnikow in Deutschland, die 14 j\u00e4hrige Freundin in den USA,, Null Steuern in Schweden und die Marihuana-T\u00fcte in Signapure haben. Deutsches Kulturgut k\u00f6nnen sie auch im Ausland pflegen, vielleicht sogar besser als in Deutschland selbst. W\u00e4hrend sie in Deutschland schon durch das anbringen einen Deutschlandflagge als potentieller Rechtsextremist in das Visier des Verfassungsschutzes geraten k\u00f6nnen, k\u00f6nnten sie z.B. in Texas beruhigt die NS Fahne an ihrem Haus anbringen und kn\u00f6pfen so auch leicht Kontakte zum lokalen Ku-Klux-Klan. Wers braucht, warum nicht? F\u00fcr manch einen Auswanderer lohnt das Auswandern schon alleine, um sich der nervigen M\u00fclltrennung zu entledigen. Neben Strand und Sonne in der Ferne, kann auch gleich eine der lokalen Sch\u00f6nheiten ihr angeschlagenes Selbstbewusstsein wiederherstellen, und das zu einem Bruchteil des Stundensatzes eines deutschen Psychologen. Doch werden wir nun etwas konkreter und erl\u00e4utern die PT Theorie von WG Hill. Diese Theorie beruht auf der F\u00fcnf-Flaggen-Strategie. Damit Sie ein wahrhaft freies, souver\u00e4nes Individuum werden k\u00f6nnen, m\u00fcssen Sie sich aus den Klauen der Regierungen befreien und sollten Ihre Interessen \u00fcber mindestens f\u00fcnf unabh\u00e4ngige L\u00e4nder\/Staaten verteilen. <\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm7\">1. Flagge STAATSB\u00dcRGERSCHAFT<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Sie sollten sich einen oder mehrere P\u00e4sse aus kleinen, neutralen und angesehenen Staaten besorgen, die nicht der Praxis anh\u00e4ngen, ihre B\u00fcrger auch im Ausland zu \u00fcberwachen oder mit Steuern zu behelligen. Im Idealfall w\u00e4hlen Sie P\u00e4sse aus, die Ihnen ein Optimum an visafreien Einreisem\u00f6glichkeiten in m\u00f6glichst vielen anderen Staaten gestatten. Am besten geeignet sind P\u00e4sse aus Staaten der Europ\u00e4ischen Union oder aus S\u00fcdamerika. In dem Land oder den L\u00e4ndern, dessen Staatsangeh\u00f6rigkeiten sie besitzen, sollten sie sich am wenigsten aufhalten!<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm7\">2. Flagge WOHNSITZ (DOMIZIL)<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Dies ist Ihr offizieller Wohnsitz: ein Land, dass Sie als echten Gebietsans\u00e4ssigen betrachtet, auch wenn Sie vielleicht tats\u00e4chlich gar nicht soviel Zeit dort zubringen m\u00f6gen. Dabei sollte es sich um einen Staat handeln, der im Ausland erzieltes Einkommen nicht besteuert, was im Endeffekt bewirkt, dass Sie nirgendwo auf der Welt eine Steuererkl\u00e4rung abzugeben brauchen. Steuerparadiese wie Turks and Caicos, Panama und Andorra sind gute, preiswerte Kandidaten.<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Wenn Sie es sich leisten k\u00f6nnen, sind aber auch die Schweiz oder Monaco zu empfehlen. Das Vereinigte K\u00f6nigreich und Irland sind ebenfalls eine \u00dcberlegung wert, wozu sie ihre steuerliche Behandlung von Ausl\u00e4ndern qualifiziert.<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm7\">3. Flagge SPIELWIESEN<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Dies sind die Orte, wo Sie den Gro\u00dfteil Ihrer Zeit verbringen m\u00f6chten. Ihre Auswahl richtet sich ganz nach dem pers\u00f6nlichen Geschmack. Vielleicht bevorzugen Sie den Lebensstil europ\u00e4ischer Metropolen, den Strand von Pattaya, vielleicht f\u00fchlen Sie sich aber auch auf einer Ranch in Neuseeland am wohlsten. Hier haben Sie keinen offiziellen Status: Sie sind nur ein Tourist \u201cauf der Durchreise\u201d. Wenn Probleme auftauchen, ziehen sie einfach weiter. Ich bevorzuge \u201e3. Welt\u201c L\u00e4nder. Bei Bagatellen wie Verkehrsdelikten k\u00f6nnen sie mit dem korrupten Polizisten oft einen g\u00fcnstigen Direktpreis aushandeln, und so den Rattenschwanz der h\u00f6heren, verbeamteten professionellen Abgreifern umgehen. Denn w\u00e4hrend die deutschen Entwicklungsgelder in den Taschen der korrupten Lokalregierung versickern, muss der Polizist seinen eigenen Cash Flow sicherstellen. Die lokalen UNO Verbrecher, die sie bisher auch mitfinanzieren durften, sind \u00fcbrigens steuerbefreit, sozusagen staatliche PTs. <\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm7\">4. Flagge GESCH\u00c4FTSSITZ<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">An diesen Orten verdienen Sie Ihr eigentliches Geld. Wenn Sie bereits eine Firma besitzen sollten, ist Ihre Wahlfreiheit in diesem Punkt m\u00f6glicherweise stark eingeschr\u00e4nkt. Dann werden Sie wohl in den sauren Apfel bei\u00dfen und einiges an Steuern und Abgaben bezahlen m\u00fcssen. Sollten Sie dagegen mit Ihren Fertigkeiten oder Ihren Know-how Ihr Geld verdienen, k\u00f6nnen Sie ein Offshore Steuerparadies zum Gesch\u00e4ftssitz machen, wodurch Sie steuerfrei ausgehen. Optimal nat\u00fcrlich f\u00fcr Berufe wie Verm\u00f6gensberater, Vertriebsingenieur, Webdesigner, Unternehmensberater oder Programmierer. In jedem Fall betreiben Sie Ihr Gesch\u00e4ft als registrierte Firma, so dass Sie nirgendwo auf der Welt eine Einkommensteuererkl\u00e4rung abzugeben brauchen. Hier bieten sich Panama IBC oder US Inc. und LLC an, alles kann leicht \u00fcber das Internet gegr\u00fcndet werden. Gut auch, dass f\u00fcr eine Panama IBC zwar eine geringe Jahresgeb\u00fchr anf\u00e4llt, man sich aber zeitraubende Dinge wie Steuererkl\u00e4rungen und Buchhaltung sparen kann. Vielleicht hat Panama einfach weniger Taxifahrer, denen der Staat das In-der-Welt-rumfliegen finanzieren muss.<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><strong><span class=\"tm7\">5. Flagge VERM\u00d6GENSSCHUTZ<\/span><\/strong><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">In diesen L\u00e4ndern halten Sie Ihre Ersparnisse und Investitionen, im eigenen Namen, durch eine Offshore Aktiengesellschaft oder durch eine Stiftung. Weitab und in Sicherheit vor den Orten, wo das Geld tats\u00e4chlich verdient oder ausgegeben wird. Auch hier halten sie sich so gut wie nie auf. Solche Staaten sollten sich auszeichnen durch ein hohes Ma\u00df an Respekt gegen\u00fcber der Privatsph\u00e4re des einzelnen, gut ausgebaute Kommunikationsnetze, professionelles Verm\u00f6gensmanagement und politische sowie wirtschaftliche Stabilit\u00e4t. So ist ihr Verm\u00f6gen gegen Rechtsstreitigkeiten und Anspr\u00fcche gieriger Exgattinnen sicher.<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Das alles muss nicht teuer sein, ja ist im Endeffekt wahrscheinlich sogar ein gutes St\u00fcck billiger als ihr bisheriger Lebensstil. Sie w\u00e4hlen eine Spielwiese mit g\u00fcnstigem Preisniveau, k\u00f6nnen sich oft die MwSt. bei Ausreise erstatten lassen und zahlen insgesamt viel weniger Steuern, wenn \u00fcberhaupt. Wie wird man PT? Gehen sie die Sache langsam an, informieren sie sich \u00fcber die rechtlichen Rahmenbedingungen, sie wollen ja ihren Steuersatz optimieren und keine Steuern hinterziehen. Ein Auslandsaufenthalt w\u00e4hrend des Studiums bietet sich als Einstieg f\u00fcr den internationalen Lebensstil an. Lernen sie sich international zu bewegen, lernen Sie Fremdsprachen, suchen sie sich internationale Freunde. Wenn sie sich f\u00fcr eine Spielwiese oder Residenz interessieren, machen sie erst mal einen Urlaub dort. Kn\u00fcpfen sie so viele Kontakte wie m\u00f6glich. Versuchen sie sich eine zweite Staatsb\u00fcrgerschaft zu zulegen. Dies k\u00f6nnten sie z.B. durch Abstammung, Konvertierung zum Judentum, Investition, Heirat, Adoption oder Einwanderung erhalten, beachten sie aber, dass sie daf\u00fcr unbedingt eine Beibehaltungsgenemigung der BRD brauchen, sonst verlieren sie den deutschen Pass automatisch. Mit zwei Staatsangeh\u00f6rigkeiten sind sie schon flexibler, k\u00f6nnen touristische Maximalaufenhtaltsdauer durch einmalige Ein- und Ausreise verl\u00e4ngern und ggf. bei Beschlagnahme ihres Reisepasses durch einen korrupten 3.Welt-Polizisten oder durch den B\u00fcrgermeister der Gemeinde Kleinmachnow, immer noch ausreisen. Vielleicht wollen sie auch nur sicherstellen, dass sie als Hooligan sich bei dem n\u00e4chsten internationalen Spiel ganz gepflegt mit anderen Hooligans gegenseitig aufs Maul hauen k\u00f6nnen und keine Ausreisebeschr\u00e4nkungen haben. Opfer von Umweltkatastrophen, Krieg oder staatlichem Genozid werden ihnen sagen k\u00f6nnen, wie wichtig eine zweite Staatsangeh\u00f6rigkeit sein kann. Staaten werden in Zukunft nur noch Provider sein, etwa so wie AOL, Acor oder Telekom. Wenn die Leistung nicht stimmt, k\u00fcndigt man. Qualifizierten Personen werden schon in wenigen Jahren die Staatsangeh\u00f6rigkeiten nachgeworfen bekommen, weil einfach nicht mehr genug Fachkr\u00e4fte und Steuerzahler da sein werden. Schauen sie sich die Staatsverschuldung, \u00dcberalterungen und Geburtsraten des Westens an. Schauen sie sich Deutschland an, welches gerade von der politischen Kaste und den 68ern gepl\u00fcndert wird. In Zukunft wird es zwangsl\u00e4ufig f\u00fcr einige Staaten hei\u00dfen: \u201eWir haben fertig\u201c. Bis dahin sollten Sie ihre ganz pers\u00f6nliche Exit-Strategie entwickelt haben!<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">\u00a0<\/span><\/p>\n<p class=\"Normal tm5 tm6\"><span class=\"tm7\">Artikel mit freundlicher Genehmigung von YR\u00a0<\/span><\/p>\n<p class=\"Normal\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8220;Nationen haben ihre alte Allmacht verloren, die patriotischen Verbindungen brechen. Nationen werden bedeutungslos, wir gehen und leben wo wir wollen. Dampfkraft erm\u00f6glicht ihnen das Gesetz zu w\u00e4hlen, unter dem sie leben wollen. Geld erm\u00f6glicht Ihnen Freiheit&#8221; Ralph Waldo Emerson, 1861 \u00a0 \u00a0Sie arbeiten lieber f\u00fcr sich selbst und nicht f\u00fcr den Staat? Sie wollen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[21,23],"tags":[],"class_list":["post-1397","post","type-post","status-publish","format-standard","hentry","category-auswandern","category-pt"],"_links":{"self":[{"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/posts\/1397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/comments?post=1397"}],"version-history":[{"count":1,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/posts\/1397\/revisions"}],"predecessor-version":[{"id":1399,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/posts\/1397\/revisions\/1399"}],"wp:attachment":[{"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/media?parent=1397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/categories?post=1397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expatcircle.com\/cms\/de\/wp-json\/wp\/v2\/tags?post=1397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}